{"id":23,"date":"2024-06-04T20:55:17","date_gmt":"2024-06-04T18:55:17","guid":{"rendered":"https:\/\/pocradio.ovh\/?p=23"},"modified":"2025-03-02T20:11:32","modified_gmt":"2025-03-02T19:11:32","slug":"benvenuti-nel-nostro-portale","status":"publish","type":"post","link":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/","title":{"rendered":"Benvenuti nel nostro portale!!"},"content":{"rendered":"\n<p><strong>Benvenuti nel nostro portale dedicato alle comunicazioni POC Radio!<\/strong><\/p>\n\n\n\n<p>Siamo felici di accogliervi in questo spazio pensato per tutti gli appassionati e i professionisti che utilizzano le POC Radio (PTT Over Cellular). Il nostro obiettivo \u00e8 offrire un punto di riferimento affidabile, dove chiunque possa trovare informazioni precise e aggiornate su questa tecnologia, condividere esperienze e accedere a risorse utili.<\/p>\n\n\n\n<p><strong>Un luogo di condivisione e crescita<\/strong><\/p>\n\n\n\n<p>Le POC Radio stanno rivoluzionando il modo di comunicare, unendo la praticit\u00e0 delle radio tradizionali con la potenza della rete cellulare. Sappiamo quanto sia importante avere un punto d\u2019incontro per scambiare opinioni, risolvere dubbi e approfondire la conoscenza di questi dispositivi. Per questo motivo, il nostro portale \u00e8 stato creato con l\u2019intento di favorire la condivisione di esperienze tra utenti, siano essi esperti del settore o neofiti che si avvicinano per la prima volta a questo mondo.<\/p>\n\n\n\n<p><strong>Un archivio sempre aggiornato<\/strong><\/p>\n\n\n\n<p>Oltre alla condivisione delle esperienze, vogliamo mettere a disposizione un archivio ricco di software, schede tecniche e documentazione sui vari dispositivi POC. Qui potrete trovare tutto ci\u00f2 che serve per configurare, aggiornare e sfruttare al meglio le vostre radio. Crediamo che un accesso rapido e ordinato a queste risorse possa fare la differenza nell\u2019uso quotidiano di questa tecnologia.<\/p>\n\n\n\n<p><strong>La nostra missione<\/strong><\/p>\n\n\n\n<p>La nostra missione \u00e8 rendere accessibile a tutti una piattaforma professionale di alto livello per uso privato, abbracciando ambiti come la famiglia, lo svago, lo sport, il tempo libero e la sicurezza di anziani e bambini. Per realizzare questo obiettivo, collaboriamo con Inrico Technologies leader globale nelle comunicazioni wireless professionali.<\/p>\n\n\n\n<p>Ti invitiamo a partecipare attivamente, a condividere la tua esperienza e a contribuire a rendere questo portale un punto di riferimento sempre pi\u00f9 completo e utile per tutti.<\/p>\n\n\n\n<p>Buona navigazione e\u2026 buon PTT a tutti!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Benvenuti nel nostro portale dedicato alle comunicazioni POC Radio! Siamo felici di accogliervi in questo spazio pensato per tutti gli appassionati e i professionisti che utilizzano le POC Radio (PTT Over Cellular). Il nostro obiettivo \u00e8 offrire un punto di riferimento affidabile, dove chiunque possa trovare informazioni precise e aggiornate su questa tecnologia, condividere esperienze [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-23","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Benvenuti nel nostro portale!! -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benvenuti nel nostro portale!! -\" \/>\n<meta property=\"og:description\" content=\"Benvenuti nel nostro portale dedicato alle comunicazioni POC Radio! Siamo felici di accogliervi in questo spazio pensato per tutti gli appassionati e i professionisti che utilizzano le POC Radio (PTT Over Cellular). Il nostro obiettivo \u00e8 offrire un punto di riferimento affidabile, dove chiunque possa trovare informazioni precise e aggiornate su questa tecnologia, condividere esperienze [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T18:55:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T19:11:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"STAFF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/\"},\"author\":{\"name\":\"STAFF\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#\\\/schema\\\/person\\\/85e856a88f09f5459b2889d34130c695\"},\"headline\":\"Benvenuti nel nostro portale!!\",\"datePublished\":\"2024-06-04T18:55:17+00:00\",\"dateModified\":\"2025-03-02T19:11:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/\"},\"wordCount\":297,\"publisher\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pocradio.ovh\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp\",\"articleSection\":[\"In Evidenza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/\",\"url\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/\",\"name\":\"Benvenuti nel nostro portale!! -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pocradio.ovh\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp\",\"datePublished\":\"2024-06-04T18:55:17+00:00\",\"dateModified\":\"2025-03-02T19:11:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pocradio.ovh\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp\",\"contentUrl\":\"https:\\\/\\\/pocradio.ovh\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp\",\"width\":1792,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/2024\\\/06\\\/04\\\/benvenuti-nel-nostro-portale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pocradio.ovh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benvenuti nel nostro portale!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#website\",\"url\":\"https:\\\/\\\/pocradio.ovh\\\/\",\"name\":\"POC RADIO ITALIA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pocradio.ovh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#organization\",\"name\":\"POC RADIO ITALIA\",\"url\":\"https:\\\/\\\/pocradio.ovh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pocradio.ovh\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/pocradio.ovh\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"width\":756,\"height\":729,\"caption\":\"POC RADIO ITALIA\"},\"image\":{\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pocradio.ovh\\\/#\\\/schema\\\/person\\\/85e856a88f09f5459b2889d34130c695\",\"name\":\"STAFF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cf06f61bbfd6240c3a70b3a682ff95bc760ee537fc9c5e1529efeed3a7d6b1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cf06f61bbfd6240c3a70b3a682ff95bc760ee537fc9c5e1529efeed3a7d6b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36cf06f61bbfd6240c3a70b3a682ff95bc760ee537fc9c5e1529efeed3a7d6b1?s=96&d=mm&r=g\",\"caption\":\"STAFF\"},\"sameAs\":[\"https:\\\/\\\/pocradio.ovh\"],\"url\":\"https:\\\/\\\/pocradio.ovh\\\/index.php\\\/author\\\/loddo-enricogmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benvenuti nel nostro portale!! -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/","og_locale":"it_IT","og_type":"article","og_title":"Benvenuti nel nostro portale!! -","og_description":"Benvenuti nel nostro portale dedicato alle comunicazioni POC Radio! Siamo felici di accogliervi in questo spazio pensato per tutti gli appassionati e i professionisti che utilizzano le POC Radio (PTT Over Cellular). Il nostro obiettivo \u00e8 offrire un punto di riferimento affidabile, dove chiunque possa trovare informazioni precise e aggiornate su questa tecnologia, condividere esperienze [&hellip;]","og_url":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/","article_published_time":"2024-06-04T18:55:17+00:00","article_modified_time":"2025-03-02T19:11:32+00:00","og_image":[{"width":1792,"height":1024,"url":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp","type":"image\/webp"}],"author":"STAFF","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#article","isPartOf":{"@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/"},"author":{"name":"STAFF","@id":"https:\/\/pocradio.ovh\/#\/schema\/person\/85e856a88f09f5459b2889d34130c695"},"headline":"Benvenuti nel nostro portale!!","datePublished":"2024-06-04T18:55:17+00:00","dateModified":"2025-03-02T19:11:32+00:00","mainEntityOfPage":{"@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/"},"wordCount":297,"publisher":{"@id":"https:\/\/pocradio.ovh\/#organization"},"image":{"@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#primaryimage"},"thumbnailUrl":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp","articleSection":["In Evidenza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/","url":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/","name":"Benvenuti nel nostro portale!! -","isPartOf":{"@id":"https:\/\/pocradio.ovh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#primaryimage"},"image":{"@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#primaryimage"},"thumbnailUrl":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp","datePublished":"2024-06-04T18:55:17+00:00","dateModified":"2025-03-02T19:11:32+00:00","breadcrumb":{"@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#primaryimage","url":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp","contentUrl":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp","width":1792,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/pocradio.ovh\/index.php\/2024\/06\/04\/benvenuti-nel-nostro-portale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pocradio.ovh\/"},{"@type":"ListItem","position":2,"name":"Benvenuti nel nostro portale!!"}]},{"@type":"WebSite","@id":"https:\/\/pocradio.ovh\/#website","url":"https:\/\/pocradio.ovh\/","name":"POC RADIO ITALIA","description":"","publisher":{"@id":"https:\/\/pocradio.ovh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pocradio.ovh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/pocradio.ovh\/#organization","name":"POC RADIO ITALIA","url":"https:\/\/pocradio.ovh\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pocradio.ovh\/#\/schema\/logo\/image\/","url":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/logo.png","contentUrl":"https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/logo.png","width":756,"height":729,"caption":"POC RADIO ITALIA"},"image":{"@id":"https:\/\/pocradio.ovh\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pocradio.ovh\/#\/schema\/person\/85e856a88f09f5459b2889d34130c695","name":"STAFF","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/36cf06f61bbfd6240c3a70b3a682ff95bc760ee537fc9c5e1529efeed3a7d6b1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36cf06f61bbfd6240c3a70b3a682ff95bc760ee537fc9c5e1529efeed3a7d6b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36cf06f61bbfd6240c3a70b3a682ff95bc760ee537fc9c5e1529efeed3a7d6b1?s=96&d=mm&r=g","caption":"STAFF"},"sameAs":["https:\/\/pocradio.ovh"],"url":"https:\/\/pocradio.ovh\/index.php\/author\/loddo-enricogmail-com\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp",1792,1024,false],"landscape":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp",1792,1024,false],"portraits":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp",1792,1024,false],"thumbnail":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi-150x150.webp",150,150,true],"medium":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi-300x171.webp",300,171,true],"large":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi-1024x585.webp",800,457,true],"1536x1536":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi-1536x878.webp",1536,878,true],"2048x2048":["https:\/\/pocradio.ovh\/wp-content\/uploads\/2025\/02\/DALL\u00b7E-2025-02-06-15.54.46-A-realistic-photo-of-a-group-of-friends-passionate-about-PoC-Push-to-Talk-Over-Cellular-radios-in-an-urban-setting.-They-are-casually-dressed-holdi.webp",1792,1024,false]},"rttpg_author":{"display_name":"STAFF","author_link":"https:\/\/pocradio.ovh\/index.php\/author\/loddo-enricogmail-com\/"},"rttpg_comment":2,"rttpg_category":"<a href=\"https:\/\/pocradio.ovh\/index.php\/category\/in-evidenza\/\" rel=\"category tag\">In Evidenza<\/a>","rttpg_excerpt":"Benvenuti nel nostro portale dedicato alle comunicazioni POC Radio! Siamo felici di accogliervi in questo spazio pensato per tutti gli appassionati e i professionisti che utilizzano le POC Radio (PTT Over Cellular). Il nostro obiettivo \u00e8 offrire un punto di riferimento affidabile, dove chiunque possa trovare informazioni precise e aggiornate su questa tecnologia, condividere esperienze&hellip;","_links":{"self":[{"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/posts\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":2,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/posts\/23\/revisions"}],"predecessor-version":[{"id":414,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/posts\/23\/revisions\/414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/media\/24"}],"wp:attachment":[{"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/media?parent=23"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/categories?post=23"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pocradio.ovh\/index.php\/wp-json\/wp\/v2\/tags?post=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}